{"id":5122,"date":"2023-09-29T07:34:31","date_gmt":"2023-09-29T07:34:31","guid":{"rendered":"http:\/\/www.ferrolcultura.gal\/?post_type=event&#038;p=5122"},"modified":"2023-09-29T07:34:38","modified_gmt":"2023-09-29T07:34:38","slug":"unha-muller-baixo-a-influencia","status":"publish","type":"event","link":"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/","title":{"rendered":"Unha muller baixo a influencia"},"content":{"rendered":"\n<p>Director: John Cassavetes<\/p>\n\n\n\n<p>Duraci\u00f3n: 155&#8242;<\/p>\n\n\n\n<p>Ano: 1974<\/p>\n\n\n\n<p>As funci\u00f3ns ter\u00e1n lugar os martes \u00e1s 20.00 horas.<\/p>\n\n\n\n<p>Entrada de balde (2 por persoa) no despacho de billetes do cinema desde o venres previo \u00e1 sesi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Director: John Cassavetes Duraci\u00f3n: 155&#8242; Ano: 1974 As funci\u00f3ns ter\u00e1n lugar os martes \u00e1s 20.00 horas. Entrada de balde (2 por persoa) no despacho de billetes do cinema desde o venres previo \u00e1 sesi\u00f3n.<\/p>\n","protected":false},"author":7,"featured_media":5123,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"eventcat":[81],"organizer":[82],"event_tags":[],"location":[80],"class_list":["post-5122","event","type-event","status-publish","has-post-thumbnail","hentry","eventcat-cine","organizer-cines-duplex","location-cine-duplex"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Unha muller baixo a influencia - Ferrol Cultura<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/\" \/>\r\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Unha muller baixo a influencia - Ferrol Cultura\" \/>\r\n<meta property=\"og:description\" content=\"Director: John Cassavetes Duraci\u00f3n: 155&#8242; Ano: 1974 As funci\u00f3ns ter\u00e1n lugar os martes \u00e1s 20.00 horas. Entrada de balde (2 por persoa) no despacho de billetes do cinema desde o venres previo \u00e1 sesi\u00f3n.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ferrol Cultura\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConcellodeFerrol\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-09-29T07:34:38+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.ferrolcultura.gal\/wp-content\/uploads\/2023\/09\/Una_mujer_bajo_la_influencia-322459835-large.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1191\" \/>\r\n\t<meta property=\"og:image:height\" content=\"737\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@ferroloficial\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/\",\"url\":\"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/\",\"name\":\"Unha muller baixo a influencia - Ferrol Cultura\",\"isPartOf\":{\"@id\":\"https:\/\/www.ferrolcultura.gal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ferrolcultura.gal\/wp-content\/uploads\/2023\/09\/Una_mujer_bajo_la_influencia-322459835-large.jpg\",\"datePublished\":\"2023-09-29T07:34:31+00:00\",\"dateModified\":\"2023-09-29T07:34:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/#primaryimage\",\"url\":\"https:\/\/www.ferrolcultura.gal\/wp-content\/uploads\/2023\/09\/Una_mujer_bajo_la_influencia-322459835-large.jpg\",\"contentUrl\":\"https:\/\/www.ferrolcultura.gal\/wp-content\/uploads\/2023\/09\/Una_mujer_bajo_la_influencia-322459835-large.jpg\",\"width\":1191,\"height\":737},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.ferrolcultura.gal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/www.ferrolcultura.gal\/index.php\/event\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unha muller baixo a influencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ferrolcultura.gal\/#website\",\"url\":\"https:\/\/www.ferrolcultura.gal\/\",\"name\":\"Ferrol Cultura\",\"description\":\"P\u00e1xina de Cultura do Concello de Ferrol\",\"publisher\":{\"@id\":\"https:\/\/www.ferrolcultura.gal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ferrolcultura.gal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ferrolcultura.gal\/#organization\",\"name\":\"Concello de Ferrol\",\"url\":\"https:\/\/www.ferrolcultura.gal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\/\/www.ferrolcultura.gal\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.ferrolcultura.gal\/wp-content\/uploads\/2023\/03\/Concello-de-Ferrol-Cultura.png\",\"contentUrl\":\"http:\/\/www.ferrolcultura.gal\/wp-content\/uploads\/2023\/03\/Concello-de-Ferrol-Cultura.png\",\"width\":3033,\"height\":419,\"caption\":\"Concello de Ferrol\"},\"image\":{\"@id\":\"https:\/\/www.ferrolcultura.gal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ConcellodeFerrol\",\"https:\/\/x.com\/ferroloficial\",\"https:\/\/www.instagram.com\/concellodeferrol\",\"https:\/\/youtube.com\/@ferrolcultura\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unha muller baixo a influencia - Ferrol Cultura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/","og_locale":"gl_ES","og_type":"article","og_title":"Unha muller baixo a influencia - Ferrol Cultura","og_description":"Director: John Cassavetes Duraci\u00f3n: 155&#8242; Ano: 1974 As funci\u00f3ns ter\u00e1n lugar os martes \u00e1s 20.00 horas. Entrada de balde (2 por persoa) no despacho de billetes do cinema desde o venres previo \u00e1 sesi\u00f3n.","og_url":"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/","og_site_name":"Ferrol Cultura","article_publisher":"https:\/\/www.facebook.com\/ConcellodeFerrol","article_modified_time":"2023-09-29T07:34:38+00:00","og_image":[{"width":1191,"height":737,"url":"https:\/\/www.ferrolcultura.gal\/wp-content\/uploads\/2023\/09\/Una_mujer_bajo_la_influencia-322459835-large.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ferroloficial","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/","url":"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/","name":"Unha muller baixo a influencia - Ferrol Cultura","isPartOf":{"@id":"https:\/\/www.ferrolcultura.gal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/#primaryimage"},"image":{"@id":"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferrolcultura.gal\/wp-content\/uploads\/2023\/09\/Una_mujer_bajo_la_influencia-322459835-large.jpg","datePublished":"2023-09-29T07:34:31+00:00","dateModified":"2023-09-29T07:34:38+00:00","breadcrumb":{"@id":"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/#primaryimage","url":"https:\/\/www.ferrolcultura.gal\/wp-content\/uploads\/2023\/09\/Una_mujer_bajo_la_influencia-322459835-large.jpg","contentUrl":"https:\/\/www.ferrolcultura.gal\/wp-content\/uploads\/2023\/09\/Una_mujer_bajo_la_influencia-322459835-large.jpg","width":1191,"height":737},{"@type":"BreadcrumbList","@id":"https:\/\/www.ferrolcultura.gal\/index.php\/event\/unha-muller-baixo-a-influencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ferrolcultura.gal\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.ferrolcultura.gal\/index.php\/event\/"},{"@type":"ListItem","position":3,"name":"Unha muller baixo a influencia"}]},{"@type":"WebSite","@id":"https:\/\/www.ferrolcultura.gal\/#website","url":"https:\/\/www.ferrolcultura.gal\/","name":"Ferrol Cultura","description":"P\u00e1xina de Cultura do Concello de Ferrol","publisher":{"@id":"https:\/\/www.ferrolcultura.gal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ferrolcultura.gal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.ferrolcultura.gal\/#organization","name":"Concello de Ferrol","url":"https:\/\/www.ferrolcultura.gal\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.ferrolcultura.gal\/#\/schema\/logo\/image\/","url":"http:\/\/www.ferrolcultura.gal\/wp-content\/uploads\/2023\/03\/Concello-de-Ferrol-Cultura.png","contentUrl":"http:\/\/www.ferrolcultura.gal\/wp-content\/uploads\/2023\/03\/Concello-de-Ferrol-Cultura.png","width":3033,"height":419,"caption":"Concello de Ferrol"},"image":{"@id":"https:\/\/www.ferrolcultura.gal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ConcellodeFerrol","https:\/\/x.com\/ferroloficial","https:\/\/www.instagram.com\/concellodeferrol","https:\/\/youtube.com\/@ferrolcultura"]}]}},"event_fields":{"start_date":"2023-09-26","start_time":"20:00","end_date":"","expire_date":"2023-09-27 00:00","start_datetime":"2023-09-26 20:00"},"_links":{"self":[{"href":"https:\/\/www.ferrolcultura.gal\/index.php\/wp-json\/wp\/v2\/event\/5122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferrolcultura.gal\/index.php\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.ferrolcultura.gal\/index.php\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/www.ferrolcultura.gal\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ferrolcultura.gal\/index.php\/wp-json\/wp\/v2\/comments?post=5122"}],"version-history":[{"count":0,"href":"https:\/\/www.ferrolcultura.gal\/index.php\/wp-json\/wp\/v2\/event\/5122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ferrolcultura.gal\/index.php\/wp-json\/wp\/v2\/media\/5123"}],"wp:attachment":[{"href":"https:\/\/www.ferrolcultura.gal\/index.php\/wp-json\/wp\/v2\/media?parent=5122"}],"wp:term":[{"taxonomy":"eventcat","embeddable":true,"href":"https:\/\/www.ferrolcultura.gal\/index.php\/wp-json\/wp\/v2\/eventcat?post=5122"},{"taxonomy":"organizer","embeddable":true,"href":"https:\/\/www.ferrolcultura.gal\/index.php\/wp-json\/wp\/v2\/organizer?post=5122"},{"taxonomy":"event_tags","embeddable":true,"href":"https:\/\/www.ferrolcultura.gal\/index.php\/wp-json\/wp\/v2\/event_tags?post=5122"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.ferrolcultura.gal\/index.php\/wp-json\/wp\/v2\/location?post=5122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}